{"id":242,"date":"2021-12-16T09:35:41","date_gmt":"2021-12-16T09:35:41","guid":{"rendered":"https:\/\/mediaboss.fr\/?p=242"},"modified":"2022-04-22T10:27:37","modified_gmt":"2022-04-22T10:27:37","slug":"envoyer-poke-facebook","status":"publish","type":"post","link":"https:\/\/mediaboss.fr\/ja\/%e3%82%bb%e3%83%b3%e3%83%89%e3%83%9d%e3%83%bc%e3%82%af%e3%83%bb%e3%83%95%e3%82%a7%e3%82%a4%e3%82%b9%e3%83%96%e3%83%83%e3%82%af\/","title":{"rendered":"\u30d5\u30a7\u30a4\u30b9\u30d6\u30c3\u30af\u3067\u30dd\u30b1\u3092\u9001\u308b\u306b\u306f\uff1f"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_post_title date=\u00a0\u00bboff\u00a0\u00bb comments=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_post_title][et_pb_text _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Vous cherchez \u00e0 savoir si Poker quelqu\u2019un sur Facebook est toujours d\u2019actualit\u00e9 en 2022 ?<\/p>\n<p>Alors vous \u00eates au bon endroit.<\/p>\n<p>Le Poke \u00e9tait une des <strong>fonctionnalit\u00e9s les plus populaires<\/strong> au d\u00e9but de Facebook.<\/p>\n<p>Les gens l\u2019utilisent normalement pour envoyer un geste d\u2019amiti\u00e9 \u00e0 la famille ou \u00e0 des amis.<\/p>\n<p>Si par exemple vous n\u2019avez pas \u00e9chang\u00e9 avec quelqu\u2019un depuis longtemps, vous pouvez le \u201cPoker\u201d sur Facebook.<\/p>\n<p>Lorsque vous Pokez quelqu\u2019un sur Facebook, il <strong>re\u00e7oit une notification<\/strong> sur Facebook et par email.<\/p>\n<p>Dans ce guide, vous allez apprendre comment Poker quelqu\u2019un sur Facebook en utilisant l\u2019application mobile Facebook.<\/p>\n<p>A quoi sert le poking ?<\/p>\n<p>Poker quelqu\u2019un sur Facebook, est-ce consid\u00e9r\u00e9 comme de la drague ?<\/p>\n<p>&nbsp;<\/p>\n<h2>Qu\u2019est-ce que \u00e7a veut dire un Poke sur Facebook ?<\/h2>\n<p>Le Poke est une fonctionnalit\u00e9 de Facebook vous permettant d\u2019envoyer une \u201ctape\u201d amicale virtuelle \u00e0 un ami sur Facebook.<\/p>\n<p>Poker quelqu\u2019un sur Facebook peut avoir <strong>plusieurs usages.<\/strong><\/p>\n<p>Vous pouvez Poker quelqu\u2019un pour lui envoyer un signe amical.<\/p>\n<p>Pour voir s\u2019il r\u00e9pond \u00e0 votre Poke par un autre Poke.<\/p>\n<p>S\u2019il vous Poke \u00e9galement, vous pouvez lui renvoyer un autre Poke et continuer\u2026<\/p>\n<p>S\u2019il ne r\u00e9pond pas \u00e0 votre Poke, alors vous n\u2019avez pas la possibilit\u00e9 lui renvoyer un second Poke.<\/p>\n<p>Si vous ne souhaitez pas r\u00e9pondre \u00e0 un Poke d\u2019un ami sur Facebook, il vous suffit de l\u2019ignorer. Il ne pourra pas vous envoyer un <strong>deuxi\u00e8me Poke<\/strong>. Vous pouvez \u00e9galement le bloquer.<\/p>\n<p>Nous allons voir maintenant comment envoyer un Poke sur Facebook.<\/p>\n<p>&nbsp;<\/p>\n<h2>Comment envoyer un Poke sur Facebook en 2022 ?<\/h2>\n<p>Pour Poker quelqu\u2019un sur Facebook, cherchez le Poke dans le Menu &gt; Recherche (loupe).<\/p>\n<p>Puis tapez \u201cPoke\u201d et validez.<\/p>\n<p>Cliquez sur \u201cEnvoyez un Poke \u00e0 vos amis\u2026\u201d.<\/p>\n<p>Et choisissez ou recherchez l\u2019ami que vous souhaitez Poker.<\/p>\n<p>Puis cliquez sur le bouton bleu \u201cPoke\u201d en face de votre ami.<\/p>\n<p>Voil\u00e0 vous avez Poke votre ami.<\/p>\n<p>Votre ami va <strong>recevoir une notification<\/strong> sur Facebook et par email.<\/p>\n<p>La fonctionnalit\u00e9 de Poke existe toujours en 2022 sur Facebook.<\/p>\n<p>Si vous ne trouvez pas le Poke, recherchez le dans la barre de recherche dans votre Menu.<\/p>\n<p>Quand vous \u00eates sur la fonctionnalit\u00e9 Pokes, vous verrez une liste d\u2019amis \u00e0 Poker.<\/p>\n<p>Si vous avez beaucoup d\u2019amis sur Facebook, vous pouvez \u00e9galement rechercher l\u2019ami \u00e0 Poker en tapant son nom ou pr\u00e9nom.<\/p>\n<p>Voici les 3 \u00e9tapes pour Poker quelqu\u2019un sur Facebook en 2022 :<\/p>\n<p>&nbsp;<\/p>\n<h3>1. Cliquez sur l&rsquo;ic\u00f4ne de recherche (loupe) dans le Menu sup\u00e9rieur<\/h3>\n<div id=\"attachment_245\" style=\"width: 491px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-245\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/comment-envoyer-poke-facebook-etape-1-481x1024.jpg\" width=\"300\" height=\"638\" alt=\"Comment envoyer un poke sur Facebook \u00e9tape 1\" class=\"wp-image-245 size-large\" \/><p id=\"caption-attachment-245\" class=\"wp-caption-text\">1. Cliquez sur l&rsquo;ic\u00f4ne de recherche (loupe) dans le Menu sup\u00e9rieur<\/p><\/div>\n<blockquote>\n<p style=\"text-align: center;\"><strong>Ouvrez l\u2019application Facebook &gt; Cliquez sur l\u2019ic\u00f4ne de recherche (loupe) dans le Menu sup\u00e9rieur.<\/strong><\/p>\n<\/blockquote>\n<p>L\u2019\u00e9tape 1 consiste \u00e0 <strong>ouvrir votre application Facebook<\/strong> mobile sur votre t\u00e9l\u00e9phone (Android ou Iphone\/iOS)<\/p>\n<p>Sur un ordinateur, allez sur l\u2019url suivante :<\/p>\n<p>Une fois l\u2019application ouverte, <strong>cliquez sur l\u2019ic\u00f4ne de recherche<\/strong> (loupe) en haut \u00e0 droite de votre t\u00e9l\u00e9phone.<\/p>\n<p>Car la fonctionnalit\u00e9 de Pokes est masqu\u00e9e par d\u00e9faut par Facebook.<\/p>\n<p>Puis passez \u00e0 l\u2019\u00e9tape 2.<\/p>\n<p>&nbsp;<\/p>\n<h3>2. Recherchez \u201cPokes\u201d et cliquez sur \u201cPokes\u201d<\/h3>\n<div id=\"attachment_246\" style=\"width: 491px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-246\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/comment-envoyer-poke-facebook-etape-2-481x1024.jpg\" width=\"300\" height=\"639\" alt=\"Comment envoyer un poke sur Facebook \u00e9tape 2\" class=\"wp-image-246 size-large\" \/><p id=\"caption-attachment-246\" class=\"wp-caption-text\">3. Cliquez sur \u201cPoke\u201d pour envoyer un Poke \u00e0 quelqu\u2019un<\/p><\/div>\n<blockquote>\n<p style=\"text-align: center;\"><strong>Recherchez \u201cPokes\u201d &gt; Cliquez sur \u201cPokes\u201d<\/strong><\/p>\n<\/blockquote>\n<p>Apr\u00e8s avoir ouverte la Recherche Facebook, <strong>tapez \u201cPokes<\/strong>\u201d pour rechercher la fonctionnalit\u00e9 de Pokes de Facebook.<\/p>\n<p>Lorsque vous voyez appara\u00eetre \u201cPokes\u201d dans la recherche, cliquez dessus.<\/p>\n<p>La fonctionnalit\u00e9 \u201cPokes\u201d appara\u00eet en premier en haut de votre \u00e9cran avec l\u2019inscription : \u201c<em>Envoyez un Poke \u00e0 vos amis et d\u00e9couvrez qui vous en a envoy\u00e9<\/em>\u201d.<\/p>\n<p><strong>Cliquez sur \u00ab\u00a0Pokes\u00a0\u00bb<\/strong> pour acc\u00e9der \u00e0 la fonctionnalit\u00e9 \u201cPokes\u201d.<\/p>\n<p>Puis passez \u00e0 l\u2019\u00e9tape finale 3.<\/p>\n<p>&nbsp;<\/p>\n<h3>3. Cliquez sur \u201cPoke\u201d pour envoyer un Poke \u00e0 quelqu\u2019un<\/h3>\n<div id=\"attachment_247\" style=\"width: 489px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-247\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/comment-envoyer-poke-facebook-etape-3-479x1024.jpg\" width=\"300\" height=\"641\" alt=\"Comment envoyer un poke sur Facebook \u00e9tape 3\" class=\"wp-image-247 size-large\" \/><p id=\"caption-attachment-247\" class=\"wp-caption-text\">3. Cliquez sur \u201cPoke\u201d pour envoyer un Poke \u00e0 quelqu\u2019un<\/p><\/div>\n<blockquote>\n<p style=\"text-align: center;\"><strong>Pour Poker quelqu\u2019un, recherchez votre ami et cliquez sur \u201cPoke\u201d \u00e0 c\u00f4t\u00e9 de son nom et pr\u00e9nom<\/strong><\/p>\n<\/blockquote>\n<p>Apr\u00e8s avoir cliqu\u00e9 sur \u201cPokes\u201d, un \u00e9cran \u201cPokes appara\u00eet avec une <strong>liste d\u2019amis.<\/strong><\/p>\n<p>En effet Facebook vous sugg\u00e8re en priorit\u00e9 des amis avec lesquels vous \u00e9changez r\u00e9guli\u00e8rement sur Facebook. C\u2019est l\u2019algorithme de Facebook qui g\u00e8re cela pour vous.<\/p>\n<p>Vous pouvez \u00e9galement rechercher un ami en particulier en utilisant l&rsquo;ic\u00f4ne de recherche (loupe) \u201c<em>Trouver des amis \u00e0 qui envoyer un Poke<\/em>\u201d.<\/p>\n<p>Une fois que vous avez trouv\u00e9 la bonne personne \u00e0 Poker, <strong>cliquez sur \u201cPoke\u201d<\/strong> \u00e0 c\u00f4t\u00e9 de son pr\u00e9nom et nom.<\/p>\n<p>Bravo, c\u2019est r\u00e9ussi ! Vous avez r\u00e9ussi \u00e0 Poker quelqu\u2019un sur Facebook !<\/p>\n<p>Votre ami va recevoir une notification sur Facebook et un email.<\/p>\n<p>Alors votre ami peut choisir de r\u00e9pondre \u00e0 votre Poke par un autre Poke ou il peut vous ignorer.<\/p>\n<p>S\u2019il r\u00e9pond \u00e0 votre Poke, vous pourrez continuer \u00e0 le Poker et ainsi de suite\u2026<\/p>\n<p>S\u2019il ne r\u00e9pond et vous ignore, vous ne pourrez plus le Poker une deuxi\u00e8me fois. Cela afin d\u2019\u00e9viter le spam et le harc\u00e8lement.<\/p>\n<p>Maintenant vous savez comment envoyer un Poke sur Facebook en 2022 !<\/p>\n<p>&nbsp;<\/p>\n<h2>Pourquoi envoyer un Poke sur Facebook ?<\/h2>\n<p>Envoyer un Poke pour signaler \u00e0 un ami sur Facebook que <strong>vous \u00eates l\u00e0<\/strong> et que vous lui faites une \u201ctape sur l\u201d\u00e9paule\u201d.<\/p>\n<p>Votre ami recevra une notification signifiant que vous l\u2019avez \u201cpok\u00e9\u201d.<\/p>\n<p>Il pourra vous \u201cpoker\u201d en retour et \u00e9ventuellement engager la conversation avec vous.<\/p>\n<p>C\u2019est une marque d\u2019attention ou une fa\u00e7on de <strong>dire bonjour<\/strong> version Facebook.<\/p>\n<p>&nbsp;<\/p>\n<h2>Envoyer un poke sur Facebook, c\u2019est draguer ?<\/h2>\n<p>Envoyer un poke ne signifie pas n\u00e9cessairement draguer quelqu\u2019un.<\/p>\n<p>C\u2019est simplement un <strong>moyen de signaler votre pr\u00e9sence<\/strong> et votre int\u00e9r\u00eat pour un(e) ami(e).<\/p>\n<p>C\u2019est comme dire \u201c<em>bonjour, je suis l\u00e0<\/em>\u201d \u00e0 une personne d\u2019une mani\u00e8re visuelle et non intrusive.<\/p>\n<p>Cela peut donc \u00eatre un moyen simple pour engager une conversation avec un ami Facebook.<\/p>\n<p>&nbsp;<\/p>\n<h2>Conclusion<\/h2>\n<p>Poker quelqu\u2019un sur Facebook est une fonctionnalit\u00e9 un peu oubli\u00e9e mais qui existe toujours en 2022.<\/p>\n<p>C\u2019est une \u00e0 <strong>manier avec pr\u00e9caution<\/strong> car cela peut \u00eatre vu comme de l\u2019impolitesse ou du harc\u00e8lement si c\u2019est mal utilis\u00e9.<\/p>\n<p>Et la fonction Poke est limit\u00e9e car elle ne permet rien d\u2019autre de plus qu\u2019une \u201ctape sur l\u2019\u00e9paule\u201d.<\/p>\n<p>Il est conseill\u00e9 de l\u2019utiliser <strong>avec parcimonie<\/strong> et d\u2019engager \u00e9ventuellement la conversation avec la personne que vous avez pok\u00e9.<\/p>\n<p>A vous d\u2019en faire bon usage !<\/p>\n<p>*<\/p>\n<p>Vous serez peut-\u00eatre int\u00e9ress\u00e9 par nos <strong>autres guides Facebook<\/strong> :<\/p>\n<ul>\n<li><a href=\"https:\/\/mediaboss.fr\/supprimer-photo-profil-facebook\/\" title=\"supprimer photo de profil facebook\">Comment Supprimer Ma Photo De Profil Facebook? (en 3 clics)<\/a><\/li>\n<li><a href=\"\/comment-recuperer-compte-facebook-sans-telephone-et-email\/\" title=\"r\u00e9cup\u00e9rer son compte Facebook sans num\u00e9ro de t\u00e9l\u00e9phone et email\">Comment r\u00e9cup\u00e9rer son compte Facebook sans num\u00e9ro de t\u00e9l\u00e9phone et sans email ?<\/a><\/li>\n<li><a href=\"\/comment-voir-les-anniversaires-sur-facebook\/\" title=\"comment voir les anniversaires sur Facebook\">Comment voir les anniversaires sur Facebook<\/a><\/li>\n<\/ul>\n<p>*<\/p>\n<p style=\"text-align: right;\"><em>Photo by Alain Pham on Unsplash<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_sidebar _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_sidebar][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; _builder_version=\u00a0\u00bb4.14.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_module=\u00a0\u00bb282&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Vous aimerez aussi :<\/h4>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00a0\u00bboff\u00a0\u00bb posts_number=\u00a0\u00bb4&Prime; include_categories=\u00a0\u00bb12&Prime; use_manual_excerpt=\u00a0\u00bboff\u00a0\u00bb excerpt_length=\u00a0\u00bb0&Prime; show_author=\u00a0\u00bboff\u00a0\u00bb show_date=\u00a0\u00bboff\u00a0\u00bb show_excerpt=\u00a0\u00bboff\u00a0\u00bb show_pagination=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh5&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb meta_font_size=\u00a0\u00bb16px\u00a0\u00bb read_more_font_size=\u00a0\u00bb16px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb meta_font_size__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb global_module=\u00a0\u00bb1657&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb][\/et_pb_blog][et_pb_team_member image_url=\u00a0\u00bbhttps:\/\/mediaboss.fr\/wp-content\/uploads\/alice-seguin-421x421px-150&#215;150.jpg\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Alice SEGUIN<\/strong><\/p>\n<p>Alice est la fondatrice de <a href=\"\/\" title=\"Mediaboss\">Mediaboss<\/a>.<\/p>\n<p>Passionn\u00e9e par les <a href=\"\/reseaux-sociaux\/\" title=\"r\u00e9seaux sociaux\">r\u00e9seaux sociaux<\/a>, elle accompagne de nombreuses entreprises dans leur strat\u00e9gie social media, messageries instantan\u00e9es, investissement, cryptomonnaies\u2026<a href=\"\/author\/alice\/\"><\/a><\/p>\n<p><a href=\"\/author\/alice\/\">Voir tous les articles d&rsquo;Alice<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;242&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;3&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Note :&quot;,&quot;legend&quot;:&quot;5\\\/5 - (3 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Comment envoyer un poke sur Facebook?&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (3 votes)    <\/div>\n    <\/div>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Vous cherchez \u00e0 savoir si Poker quelqu\u2019un sur Facebook est toujours d\u2019actualit\u00e9 en 2022 ? Alors vous \u00eates au bon endroit. Le Poke \u00e9tait une des fonctionnalit\u00e9s les plus populaires au d\u00e9but de Facebook. Les gens l\u2019utilisent normalement pour envoyer un geste d\u2019amiti\u00e9 \u00e0 la famille ou \u00e0 des amis. Si par exemple vous n\u2019avez [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":244,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"Comment Envoyer Un Poke Sur Facebook En %%currentyear%%? Mediaboss","_seopress_titles_desc":"Vous cherchez \u00e0 envoyer un Poke sur Facebook en %%currentyear%% ? Qu&#039;est-ce qu&#039;un Poke ? Voici le guide \u00e9tape par \u00e9tape pour &quot;poker&quot; un ami via t\u00e9l\u00e9phone sur Facebook.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1280","footnotes":""},"categories":[12],"tags":[],"class_list":["post-242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-facebook"],"_links":{"self":[{"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/posts\/242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/comments?post=242"}],"version-history":[{"count":0,"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/posts\/242\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/media\/244"}],"wp:attachment":[{"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/media?parent=242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/categories?post=242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mediaboss.fr\/ja\/wp-json\/wp\/v2\/tags?post=242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}