{"id":1709,"date":"2022-04-26T07:14:17","date_gmt":"2022-04-26T07:14:17","guid":{"rendered":"https:\/\/mediaboss.fr\/?p=1709"},"modified":"2022-04-27T15:44:23","modified_gmt":"2022-04-27T15:44:23","slug":"comptes-business-ne-peuvent-pas-etre-prives-instagram","status":"publish","type":"post","link":"https:\/\/mediaboss.fr\/ru\/%d0%b1%d0%b8%d0%b7%d0%bd%d0%b5%d1%81-%d0%b0%d0%ba%d0%ba%d0%b0%d1%83%d0%bd%d1%82%d1%8b-%d0%bc%d0%be%d0%b6%d0%bd%d0%be-%d0%b1%d1%8b%d1%82%d1%8c-%d0%bf%d1%80%d0%b8%d0%b2%d0%b8%d0%bb%d0%b5%d0%b3%d0%b8\/","title":{"rendered":"\u041a\u0430\u043a \u0440\u0435\u0448\u0438\u0442\u044c \u043f\u0440\u043e\u0431\u043b\u0435\u043c\u0443 \"\u0411\u0438\u0437\u043d\u0435\u0441-\u0430\u043a\u043a\u0430\u0443\u043d\u0442\u044b \u043d\u0435 \u043c\u043e\u0433\u0443\u0442 \u0431\u044b\u0442\u044c \u043f\u0440\u0438\u0432\u0430\u0442\u043d\u044b\u043c\u0438\" \u0432 Instagram?"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_post_title date=\u00a0\u00bboff\u00a0\u00bb comments=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_post_title][et_pb_text _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Vous voyez une erreur <strong>\u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb<\/strong> sur Instagram en 2022? ?<\/p>\n<p>Voici la partie 2 du message d&rsquo;erreur : <em>\u00ab\u00a0Si vous souhaitez que votre compte soit priv\u00e9, veuillez d&rsquo;abord revenir \u00e0 un compte personnel.\u00a0\u00bb<\/em><\/p>\n<p>Un compte business\/professionnel Instagram vous permet d&rsquo;acc\u00e9der aux statistiques de votre profil et activit\u00e9 Instagram.<\/p>\n<p style=\"text-align: center;\">A LIRE : notre guide sur <a href=\"https:\/\/mediaboss.fr\/comment-voir-les-statistiques-sur-instagram\/\" target=\"_blank\" rel=\"noopener\" title=\"comment voir les statistiques sur instagram\">comment voir les statistiques sur Instagram en 2022<\/a>.<\/p>\n<p>Les stats vous aideront \u00e0 comprendre qui s&rsquo;engage avec votre entreprise.<\/p>\n<p>En outre, vous aurez acc\u00e8s au tableau de bord professionnel.<\/p>\n<p>Dans le tableau de bord professionnel, vous pouvez suivre vos performances et explorer les ressources par Instagram.<\/p>\n<p>Si vous avez un compte Instagram personnel, <strong>vous pourrez le rendre priv\u00e9<\/strong>\u00a0 &#8211; mais qu&rsquo;en est-il d&rsquo;un compte professionnel ?<\/p>\n<p>Dans ce guide, vous apprendrez si un compte professionnel peut \u00eatre priv\u00e9 sur Instagram et comment corriger \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb en <strong>6 \u00e9tapes simples et rapides.<\/strong><\/p>\n<ul>\n<li>Un compte business\/professionnel peut-il \u00eatre priv\u00e9 sur Instagram?<\/li>\n<li>Comment r\u00e9soudre le message \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb sur Instagram?<\/li>\n<\/ul>\n<p style=\"text-align: right;\"><em>Article mis \u00e0 jour en <strong>Avril 2022<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Un compte business\/professionnel peut-il \u00eatre priv\u00e9 sur Instagram en 2022?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-00-message.jpg\" width=\"392\" height=\"816\" alt=\"les comptes business ne peuvent pas \u00eatre priv\u00e9s\" class=\"wp-image-1723 aligncenter size-full\" srcset=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-00-message.jpg 392w, https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-00-message-144x300.jpg 144w\" sizes=\"(max-width: 392px) 100vw, 392px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Les comptes business\/professionnel <strong>ne peuvent pas \u00eatre priv\u00e9s<\/strong> sur Instagram en 2022.<\/p>\n<p>Non, un compte businessne peut pas \u00eatre priv\u00e9 sur Instagram.<\/p>\n<p>Selon Instagram, vous pouvez <strong>uniquement d\u00e9finir un compte personnel comme priv\u00e9<\/strong>.<\/p>\n<p>Si vous essayez de d\u00e9finir un compte professionnel comme priv\u00e9, vous obtiendrez l&rsquo;erreur \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb.<\/p>\n<p>Par cons\u00e9quent, si vous voulez d\u00e9finir votre compte professionnel Instagram comme priv\u00e9, vous devez d&rsquo;abord le transformer en compte personnel.<\/p>\n<p>Passez \u00e0 la section suivante pour apprendre comment transformer votre compte business en compte personnel en 2022.<\/p>\n<p>&nbsp;<\/p>\n<h2>Comment r\u00e9soudre le message \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb sur Instagram en 2022?<\/h2>\n<p>Pour r\u00e9soudre le probl\u00e8me \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb sur Instagram, vous devez <strong>transformer votre compte busines\u00a0 \u00e0 un compte personnel.<\/strong><\/p>\n<p>Une fois que vous aurez bascul\u00e9 vers un compte personnel, vous serez en mesure de d\u00e9finir votre compte comme priv\u00e9.<\/p>\n<p>En effet, les comptes business ne peuvent pas \u00eatre d\u00e9finis comme priv\u00e9s.<\/p>\n<p>Pour passer votre compte Instagram \u00e0 un compte personnel, <strong>acc\u00e9dez \u00e0 votre profil Instagram &gt; Profil &gt; Menu &gt; Param\u00e8tres &gt; Compte &gt; Changer de type de compte &gt; Passer \u00e0 un compte personnel.<\/strong><\/p>\n<p>Enfin, naviguez jusqu&rsquo;\u00e0 \u00ab\u00a0Confidentialit\u00e9\u00a0\u00bb et activez \u00ab\u00a0Compte priv\u00e9\u00a0\u00bb.<\/p>\n<p>Voici comment corriger l&rsquo;erreur \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb sur Instagram en <strong>6 \u00e9tapes d\u00e9taill\u00e9es<\/strong> (avec captures d&rsquo;\u00e9cran) :<\/p>\n<p>&nbsp;<\/p>\n<h3>1. Allez sur votre profil Instagram et ouvrez le Menu<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-01.jpg\" width=\"400\" height=\"852\" alt=\"profil Instagram et ouvrez le Menu\" class=\"wp-image-1722 aligncenter size-full\" srcset=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-01.jpg 411w, https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-01-141x300.jpg 141w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Tout d&rsquo;abord, ouvrez l&rsquo;application mobile Instagram sur votre t\u00e9l\u00e9phone et connectez-vous \u00e0 votre compte Instagram.<\/p>\n<p>La m\u00e9thode s&rsquo;applique pour les <strong>iPhone<\/strong>\/iOS et les t\u00e9l\u00e9phones <strong>Android<\/strong> : Samsung, Huawei, Xiaomoi, Oppo, Realme&#8230;<\/p>\n<p>Acc\u00e9dez \u00e0 votre Profil Instagram en tapant <strong>sur votre photo de profil<\/strong> dans la barre de navigation inf\u00e9rieure.<\/p>\n<p>Une fois que vous \u00eates sur votre profil Instagram, vous devez ouvrir le Menu (3 barres horizontales).<\/p>\n<p>Pour ouvrir le menu, tapez sur l&rsquo;ic\u00f4ne du Menu dans la barre de navigation sup\u00e9rieure.<\/p>\n<p>&nbsp;<\/p>\n<h3>2. Allez dans vos Param\u00e8tres<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-02.jpg\" width=\"400\" height=\"800\" alt=\"Param\u00e8tres instagram\" class=\"wp-image-1721 aligncenter size-full\" srcset=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-02.jpg 430w, https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-02-150x300.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Apr\u00e8s avoir tap\u00e9 sur l&rsquo;ic\u00f4ne du Menu, le Menu s&rsquo;ouvre.<\/p>\n<p>Le Menu contient plusieurs options.<\/p>\n<p>Il s&rsquo;agit notamment de \u00ab\u00a0Param\u00e8tres\u00a0\u00bb, \u00ab\u00a0Archives\u00a0\u00bb, \u00ab\u00a0Votre activit\u00e9\u00a0\u00bb&#8230;<\/p>\n<p>Pour modifier votre type de compte, vous devez vous rendre dans vos Param\u00e8tres.<\/p>\n<p><strong>S\u00e9lectionnez\u00a0 \u00ab\u00a0Param\u00e8tres\u00a0\u00bb<\/strong> pour acc\u00e9der \u00e0 la page des Param\u00e8tres.<\/p>\n<p>&nbsp;<\/p>\n<h3>3. S\u00e9lectionnez \u00ab\u00a0Compte\u00a0\u00bb<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-03.jpg\" width=\"399\" height=\"848\" alt=\"S\u00e9lectionnez  \" compte=\"\" class=\"wp-image-1720 aligncenter size-full\" srcset=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-03.jpg 407w, https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-03-141x300.jpg 141w\" sizes=\"(max-width: 399px) 100vw, 399px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Apr\u00e8s avoir s\u00e9lectionner\u00a0 \u00ab\u00a0Param\u00e8tres\u00a0\u00bb, vous acc\u00e9dez \u00e0 la page des Param\u00e8tres.<\/p>\n<p>La page des Param\u00e8tres contient plusieurs options.<\/p>\n<p>Cela inclut \u00ab\u00a0Confidentialit\u00e9\u00a0\u00bb, \u00ab\u00a0S\u00e9curit\u00e9\u00a0\u00bb, \u00ab\u00a0Paiements\u00a0\u00bb&#8230;<\/p>\n<p>Faites d\u00e9filer vers le bas et <strong>s\u00e9lectionnez sur \u00ab\u00a0Compte\u00a0\u00bb<\/strong> pour acc\u00e9der aux param\u00e8tres de votre compte.<\/p>\n<p>&nbsp;<\/p>\n<h3>4. Choisissez\u00a0 \u00ab\u00a0Changer de type de compte\u00a0\u00bb<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-04.jpg\" width=\"401\" height=\"857\" alt=\"Changer de type de compte instagram\" class=\"wp-image-1719 aligncenter size-full\" srcset=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-04.jpg 407w, https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-04-140x300.jpg 140w\" sizes=\"(max-width: 401px) 100vw, 401px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Apr\u00e8s avoir s\u00e9lectionn\u00e9\u00a0 \u00ab\u00a0Compte\u00a0\u00bb, vous atterrirez sur les Param\u00e8tres de votre compte.<\/p>\n<p>Il y a plusieurs options parmi lesquelles vous pouvez choisir.<\/p>\n<p>Cela inclut \u00ab\u00a0Synchronisation des contacts\u00a0\u00bb, \u00ab\u00a0Partage sur d&rsquo;autres application\u00a0\u00bb, \u00ab\u00a0Utilisation des donn\u00e9es cellulaires\u00a0\u00bb&#8230;<\/p>\n<p>En bas de la page, vous verrez 2 liens : \u00ab\u00a0Changer de type de compte\u00a0\u00bb et \u00ab\u00a0Ajouter un nouveau compte professionnel\u00a0\u00bb.<\/p>\n<p><strong>Choisissez \u00ab\u00a0Changer de type de compte\u00a0\u00bb<\/strong> pour changer votre type de compte.<\/p>\n<p>&nbsp;<\/p>\n<h3>5. S\u00e9lectionnez \u00ab\u00a0Passer \u00e0 un compte personnel\u00a0\u00bb<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-05.jpg\" width=\"347\" height=\"700\" alt=\"Passer \u00e0 un compte personnel instagram\" class=\"wp-image-1718 alignnone size-full\" srcset=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-05.jpg 432w, https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-05-149x300.jpg 149w\" sizes=\"(max-width: 347px) 100vw, 347px\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-06.jpg\" width=\"329\" height=\"700\" alt=\"Passer \u00e0 un compte personnel\" class=\"wp-image-1717 alignnone size-full\" srcset=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-06.jpg 405w, https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-06-141x300.jpg 141w\" sizes=\"(max-width: 329px) 100vw, 329px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Apr\u00e8s avoir cliqu\u00e9 sur \u00ab\u00a0Changer de type de compte\u00a0\u00bb, plusieurs options s&rsquo;offrent \u00e0 vous.<\/p>\n<p>Il s&rsquo;agit notamment de \u00ab\u00a0Passer \u00e0 un compte personnel\u00a0\u00bb et \u00ab\u00a0Passer \u00e0 un compte Creator\u00a0\u00bb.<\/p>\n<p>Pour d\u00e9finir votre compte professionnel Instagram comme priv\u00e9, vous devez le <strong>changer en compte personnel<\/strong>.<\/p>\n<p>En effet, les comptes business Instagram ne peuvent pas \u00eatre d\u00e9finis comme priv\u00e9s.<\/p>\n<p><strong>S\u00e9lectionnez sur \u00ab\u00a0Passer \u00e0 un compte personnel\u00a0\u00bb<\/strong> pour passer \u00e0 un compte personnel.<\/p>\n<p><span style=\"color: #e02b20;\">IMPORTANT :<\/span><\/p>\n<p><span style=\"color: #e02b20;\"><em>\u00ab\u00a0Lorsque vous revenez \u00e0 un compte personnel, les statistiques fournies dans l&rsquo;application sont d\u00e9sactiv\u00e9es et les statistiques de l&rsquo;ensemble de votre contenu, y compris de vos publicit\u00e9s, sont supprim\u00e9s d\u00e9finitivement\u00a0\u00bb<\/em><\/span><\/p>\n<p><span style=\"color: #e02b20;\">Soyez donc prudent et r\u00e9fl\u00e9chissez bien avant de passer \u00e0 un compte personnel !<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3>6. Passer \u00e0 un compte priv\u00e9<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-06-b.jpg\" width=\"430\" height=\"790\" alt=\"Passer \u00e0 un compte priv\u00e9 instagram\" class=\"wp-image-1726 aligncenter size-full\" srcset=\"https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-06-b.jpg 430w, https:\/\/mediaboss.fr\/wp-content\/uploads\/les-comptes-business-ne-peuvent-pas-etre-prives-instagram-guide-etape-06-b-163x300.jpg 163w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Derni\u00e8re \u00e9tape : apr\u00e8s avoir s\u00e9lectionn\u00e9 \u00ab\u00a0Passer \u00e0 un compte personnel\u00a0\u00bb, vous pourrez d\u00e9finir votre compte comme priv\u00e9!<\/p>\n<p>Pour ce faire, acc\u00e9dez aux\u00a0 Param\u00e8tres &gt; Confidentialit\u00e9.<\/p>\n<p>Sous \u00ab\u00a0Confidentialit\u00e9 du compte\u00a0\u00bb, vous verrez une option \u00ab\u00a0Compte priv\u00e9\u00a0\u00bb.<\/p>\n<p><strong>Activez \u00ab\u00a0Compte priv\u00e9\u00a0\u00bb et tapez sur \u00ab\u00a0Passer en priv\u00e9\u00a0\u00bb<\/strong> pour d\u00e9finir votre compte Instagram en priv\u00e9.<\/p>\n<p>Maintenant, les gens devront demander \u00e0 suivre votre compte.<\/p>\n<p>Et vous devez les accepter un par un afin de les autoriser \u00e0 voir vos publications Instagram.<\/p>\n<p>Puisque votre compte Instagram est un compte personnel, vous n&rsquo;obtiendrez plus l&rsquo;erreur en 2022 \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb !<\/p>\n<p>Bravo; vous avez r\u00e9ussi !<\/p>\n<p>&nbsp;<\/p>\n<h2>Conclusion<\/h2>\n<p><span style=\"color: #e02b20;\">Attention : sachez que si vous passez votre compte business\/professionnel Instagram \u00e0 un compte priv\u00e9, vous perdez l&rsquo;acc\u00e8s \u00e0 vos statistiques d\u00e9taill\u00e9es !<\/span><\/p>\n<p><span style=\"color: #e02b20;\">Pensez-y avant de transformer votre compte. <\/span><\/p>\n<p><span style=\"color: #e02b20;\">Notez que vous perdez \u00e9galement tout l&rsquo;historique de vos stats !<\/span><\/p>\n<p>Si vous consultez fr\u00e9quemment vos stats Instagram, le passage \u00e0 un compte personnel sur Instagram peut \u00eatre une mauvaise id\u00e9e.<\/p>\n<p>Si vous ne consultez pas vos statistiques , vous pouvez passer \u00e0 un compte personnel avant de le d\u00e9finir en compte priv\u00e9 .<\/p>\n<p>En effet, vous pouvez revenir \u00e0 un compte professionnel \u00e0 tout moment.<\/p>\n<p>&nbsp;<\/p>\n<h2>Autres questions pos\u00e9es concernant Instagram en 2022<\/h2>\n<p>&nbsp;<\/p>\n<h3>Comment passer d&rsquo;un compte Instagram professionnel a un compte priv\u00e9 en 2022?<\/h3>\n<p>\u00a0Pour passer d&rsquo;un compte professionnel \u00e0 un compte priv\u00e9 Instagram en 2022: allez dans <strong>Profil &gt; Menu &gt; Param\u00e8tres &gt; Confidentialit\u00e9 &gt; section 1. Confidentialit\u00e9 du compte &gt; Activez l&rsquo;option Compte priv\u00e9.<\/strong><\/p>\n<p>En cas de message d&rsquo;erreur \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb, vous devez transformer votre compte professionnel\/business en compte personnel \u00e0 l&rsquo;aide du guide d\u00e9taill\u00e9 ci-dessus en 6 \u00e9tapes.<\/p>\n<p>&nbsp;<\/p>\n<h3>Quelle est la diff\u00e9rence entre un compte normal et un compte professionnel sur Instagram ?<\/h3>\n<p>Sur Instagram, le compte normal (ou compte personnel) est le compte Instagram par d\u00e9faut avec des fonctionnalit\u00e9s limit\u00e9es.<\/p>\n<p>Le compte professionnel Instagram vous permet d&rsquo;acc\u00e9der \u00e0 des fonctionnalit\u00e9s suppl\u00e9mentaires : <a href=\"https:\/\/mediaboss.fr\/comment-voir-les-statistiques-sur-instagram\/\">statistiques d\u00e9taill\u00e9es de vos publications<\/a>, activit\u00e9, audiences, impressions, engagement&#8230;\u00a0<\/p>\n<p>&nbsp;<\/p>\n<h3>Pourquoi mettre son compte Instagram en priv\u00e9 ?<\/h3>\n<p>Mettre votre compte Instagram en priv\u00e9 vous permet de limiter l&rsquo;acc\u00e8s \u00e0 votre compte et publications et de s\u00e9lectionner vos abonn\u00e9s.<\/p>\n<p>Cela peut \u00eatre utile afin de prot\u00e9ger votre vie priv\u00e9e ou si vous publiez des contenus borderline (NSFW Not Safe For Work) par exemple.<\/p>\n<p>Cela vous \u00e9vitera d&rsquo;\u00eatre d\u00e9nonc\u00e9 et suspendu par Instagram pour non respect des r\u00e8gles de la communaut\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p>*<\/p>\n<p>D\u00e9couvrez notre <a href=\"https:\/\/mediaboss.fr\/vocabulaire-instagram\/\" target=\"_blank\" rel=\"noopener\" title=\"lexique et vocabulaire instagram\">lexique 2022 pour tout comprendre du vocabulaire d&rsquo;Instagram<\/a> en 2022.<\/p>\n<p>*<\/p>\n<p>Et vous serez \u00e9galement int\u00e9ress\u00e9 par nos autres<span>\u00a0<\/span><strong>guides <a href=\"https:\/\/mediaboss.fr\/reseaux-sociaux\/instagram\/\" target=\"_blank\" rel=\"noopener\" title=\"tous les articles et guides instagram\">Instagram<\/a> 2022<\/strong>:<\/p>\n<ul>\n<li><a href=\"https:\/\/mediaboss.fr\/voir-vos-likes-instagram\/\" title=\"voir mes propres likes instagram\">Comment Voir Vos Likes\/J\u2019aime sur Instagram? (en 4 clics)<\/a><\/li>\n<li><a href=\"https:\/\/mediaboss.fr\/supprimer-conversation-instagram-2-cotes\/\" title=\"comment supprimer une conversation instagram des deux c\u00f4t\u00e9s\">Comment Supprimer Une Conversation Instagram Des 2 C\u00f4t\u00e9s? (Simplement)<\/a><\/li>\n<li><a href=\"https:\/\/mediaboss.fr\/compte-instagram-supprime\/\" title=\"compte instagram supprim\u00e9\">Pourquoi Instagram A Supprim\u00e9 Mon Compte Sans Raison?<\/a><\/li>\n<\/ul>\n<p>*<\/p>\n<p>N\u2019h\u00e9sitez pas \u00e0 nous <a href=\"\/contact\/\" title=\"contacter Mediaboss\">contacter<\/a> si vous avez des remarques ou questions sur le sujet.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_sidebar _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_sidebar][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>Vous aimerez aussi :<\/h4>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00a0\u00bboff\u00a0\u00bb posts_number=\u00a0\u00bb4&Prime; include_categories=\u00a0\u00bb11&Prime; use_manual_excerpt=\u00a0\u00bboff\u00a0\u00bb excerpt_length=\u00a0\u00bb0&Prime; show_author=\u00a0\u00bboff\u00a0\u00bb show_date=\u00a0\u00bboff\u00a0\u00bb show_excerpt=\u00a0\u00bboff\u00a0\u00bb show_pagination=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_level=\u00a0\u00bbh5&Prime; body_font_size=\u00a0\u00bb16px\u00a0\u00bb meta_font_size=\u00a0\u00bb16px\u00a0\u00bb read_more_font_size=\u00a0\u00bb16px\u00a0\u00bb global_module=\u00a0\u00bb1179&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb meta_font_size__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb][\/et_pb_blog][et_pb_team_member image_url=\u00a0\u00bbhttps:\/\/mediaboss.fr\/wp-content\/uploads\/alice-seguin-421x421px-150&#215;150.jpg\u00a0\u00bb facebook_url=\u00a0\u00bbhttps:\/\/www.facebook.com\/mediaboss.fr\u00a0\u00bb twitter_url=\u00a0\u00bbhttps:\/\/twitter.com\/Alice98327791&Prime; linkedin_url=\u00a0\u00bbwww.linkedin.com\/in\/alice-seguin\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb global_module=\u00a0\u00bb91&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]<\/p>\n<p><strong>Alice SEGUIN<\/strong><\/p>\n<p>Alice est la fondatrice de <a title=\"Mediaboss\" href=\"\/\">Mediaboss<\/a>.<\/p>\n<p>Passionn\u00e9e par les <a title=\"r\u00e9seaux sociaux\" href=\"\/reseaux-sociaux\/\">r\u00e9seaux sociaux<\/a>, elle accompagne de nombreuses entreprises dans leur strat\u00e9gie social media, messageries instantan\u00e9es, investissement, cryptomonnaies\u2026<\/p>\n<p>Retrouvez-moi sur mes r\u00e9seaux sociaux :<\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-right kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;right&quot;,&quot;id&quot;:&quot;1709&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;8&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Note :&quot;,&quot;legend&quot;:&quot;4.7\\\/5 - (8 \u0433\u043e\u043b\u043e\u0441\u043e\u0432)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Comment R\u00e9soudre \\u0026quot;Les comptes business ne peuvent pas \u00eatre priv\u00e9s\\u0026quot; sur Instagram?&quot;,&quot;width&quot;:&quot;133.8&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 133.8px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            4.7\/5 - (8 \u0433\u043e\u043b\u043e\u0441\u043e\u0432)    <\/div>\n    <\/div>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>","protected":false},"excerpt":{"rendered":"<p>Vous voyez une erreur \u00ab\u00a0Les comptes business ne peuvent pas \u00eatre priv\u00e9s\u00a0\u00bb sur Instagram en 2022? ? Voici la partie 2 du message d&rsquo;erreur : \u00ab\u00a0Si vous souhaitez que votre compte soit priv\u00e9, veuillez d&rsquo;abord revenir \u00e0 un compte personnel.\u00a0\u00bb Un compte business\/professionnel Instagram vous permet d&rsquo;acc\u00e9der aux statistiques de votre profil et activit\u00e9 Instagram. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"Comment R\u00e9soudre &quot;Les comptes business ne peuvent pas \u00eatre priv\u00e9s&quot; sur Instagram en %%currentyear%%? Mediaboss","_seopress_titles_desc":"D\u00e9couvrez comment r\u00e9soudre facilement en %%currentyear%% l&#039;erreur &quot;Les comptes business ne peuvent pas \u00eatre priv\u00e9s&quot; sur Instagram. Guide d\u00e9taill\u00e9 en 6 \u00e9tapes simples et rapides","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"les comptes business ne peuvent pas \u00eatre priv\u00e9s","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1280","footnotes":""},"categories":[11],"tags":[],"class_list":["post-1709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-instagram"],"_links":{"self":[{"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/posts\/1709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/comments?post=1709"}],"version-history":[{"count":0,"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/posts\/1709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/media\/1733"}],"wp:attachment":[{"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/media?parent=1709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/categories?post=1709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mediaboss.fr\/ru\/wp-json\/wp\/v2\/tags?post=1709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}